{"id":7029,"date":"2016-06-22T18:42:36","date_gmt":"2016-06-22T22:42:36","guid":{"rendered":"http:\/\/www.organogold.com\/ca-zh\/body-management\/"},"modified":"2023-07-04T11:02:34","modified_gmt":"2023-07-04T18:02:34","slug":"body-management","status":"publish","type":"page","link":"https:\/\/organogold.com\/ca-zh\/body-management\/","title":{"rendered":"Body Management"},"content":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-926a56fcc94e68f\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-536a56fcc94ee76\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma.jpg 550w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma-150x150.jpg 150w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma-300x300.jpg 300w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/ganoderma-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1542154016059{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse so-prodnum-801-CA ix-prodnum-1138\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">\u7acb\u5373\u8d2d\u4e70<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ganoderma-lucidum\/\">\u7522\u54c1\u8a73\u60c5<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;\u9748\u829d\u81a0\u56ca&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-26a56fcc94ef62\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-716a56fcc94f49b\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"600\" height=\"600\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/spore_powder.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/spore_powder.jpg 600w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/spore_powder-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/spore_powder-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/spore_powder-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/spore_powder-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/spore_powder-80x80.jpg 80w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1542154104150{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse so-prodnum-803-CA ix-prodnum-1141\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">\u7acb\u5373\u8d2d\u4e70<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ganoderma-spore-powder\/\">\u7522\u54c1\u8a73\u60c5<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;\u9748\u829d\u5b62\u5b50\u7c89\u81a0\u56ca&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-876a56fcc94f53b\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-406a56fcc94fabd\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium.jpg 550w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-150x150.jpg 150w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-300x300.jpg 300w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1542154063834{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse so-prodnum-802-CA ix-prodnum-1139\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">\u7acb\u5373\u8d2d\u4e70<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ganoderma-lucidum-mycelium\/\">\u7522\u54c1\u8a73\u60c5<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;\u9748\u829d\u83cc\u7d72\u9ad4\u81a0\u56ca&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-426a56fcc94fb5f\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-56a56fcc950071\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"600\" height=\"600\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-choco-2.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-choco-2.jpg 600w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-choco-2-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-choco-2-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-choco-2-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-choco-2-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-choco-2-80x80.jpg 80w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1542154213907{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse so-prodnum-1102CA ix-prodnum-1143\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">\u7acb\u5373\u8d2d\u4e70<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ogx-fenix-rich-chocolate\/\">\u7522\u54c1\u8a73\u60c5<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;OGX FENIX&#x2122; \u6fc3\u90c1\u5de7\u514b\u529b&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-946a56fcc950111\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-626a56fcc9505f1\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"600\" height=\"600\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-vanilla-2.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-vanilla-2.jpg 600w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-vanilla-2-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-vanilla-2-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-vanilla-2-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-vanilla-2-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/08\/ogx-vanilla-2-80x80.jpg 80w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1542153996218{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse so-prodnum-1101CA ix-prodnum-1142\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">\u7acb\u5373\u8d2d\u4e70<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ogx-fenix-creamy-vanilla\/\">\u7522\u54c1\u8a73\u60c5<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;OGX FENIX&#x2122; \u5976\u8102\u9999\u8349&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-256a56fcc950683\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-656a56fcc950870\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium.jpg 550w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-150x150.jpg 150w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-300x300.jpg 300w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/mycelium-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1542154063834{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse so-prodnum-802-CA ix-prodnum-1139\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">\u7acb\u5373\u8d2d\u4e70<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ganoderma-lucidum-mycelium\/\">\u7522\u54c1\u8a73\u60c5<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;\u9748\u829d\u83cc\u7d72\u9ad4\u81a0\u56ca&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-1006a56fcc950903\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-376a56fcc950dff\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed.jpg 550w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed-150x150.jpg 150w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed-300x300.jpg 300w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/grapeseed-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1542154196013{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse so-prodnum-804-CA ix-prodnum-1137\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">\u7acb\u5373\u8d2d\u4e70<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/grapeseed\/\">\u7522\u54c1\u8a73\u60c5<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;\u8461\u8404\u7c7d\u6cb9&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;\u9748\u829d\u81a0\u56ca&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;\u9748\u829d\u5b62\u5b50\u7c89\u81a0\u56ca&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;\u9748\u829d\u83cc\u7d72\u9ad4\u81a0\u56ca&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][\/vc_column][\/vc_row][vc_row disable_element=&#8221;yes&#8221;][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Body Management - Organo Gold<\/title>\n<meta name=\"description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.organogold.com\/ca-zh\/body-management\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Body Management - Organo Gold\" \/>\n<meta property=\"og:description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.organogold.com\/ca-zh\/body-management\/\" \/>\n<meta property=\"og:site_name\" content=\"Organo Gold\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/organogold\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T18:02:34+00:00\" \/>\n<meta property=\"fb:app_id\" content=\"1781016228881841\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OrganoGold\" \/>\n<meta name=\"twitter:site\" content=\"@OrganoGold\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/organogold.com\/ca-zh\/#website\",\"url\":\"https:\/\/organogold.com\/ca-zh\/\",\"name\":\"Organo Gold\",\"description\":\"Organo Gold\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/organogold.com\/ca-zh\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.organogold.com\/ca-zh\/body-management\/#webpage\",\"url\":\"http:\/\/www.organogold.com\/ca-zh\/body-management\/\",\"name\":\"Body Management - Organo Gold\",\"isPartOf\":{\"@id\":\"https:\/\/organogold.com\/ca-zh\/#website\"},\"datePublished\":\"2016-06-22T22:42:36+00:00\",\"dateModified\":\"2023-07-04T18:02:34+00:00\",\"description\":\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.organogold.com\/ca-zh\/body-management\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/organogold.com\/ca-zh\/wp-json\/wp\/v2\/pages\/7029"}],"collection":[{"href":"https:\/\/organogold.com\/ca-zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/organogold.com\/ca-zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/organogold.com\/ca-zh\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/organogold.com\/ca-zh\/wp-json\/wp\/v2\/comments?post=7029"}],"version-history":[{"count":6,"href":"https:\/\/organogold.com\/ca-zh\/wp-json\/wp\/v2\/pages\/7029\/revisions"}],"predecessor-version":[{"id":89249,"href":"https:\/\/organogold.com\/ca-zh\/wp-json\/wp\/v2\/pages\/7029\/revisions\/89249"}],"wp:attachment":[{"href":"https:\/\/organogold.com\/ca-zh\/wp-json\/wp\/v2\/media?parent=7029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}