{"id":3581,"date":"2016-06-22T18:42:36","date_gmt":"2016-06-22T22:42:36","guid":{"rendered":"http:\/\/www.organogold.com\/ke-en\/body-management\/"},"modified":"2018-03-21T08:50:05","modified_gmt":"2018-03-21T15:50:05","slug":"body-management","status":"publish","type":"page","link":"https:\/\/organogold.com\/ke-en\/body-management\/","title":{"rendered":"Body Management"},"content":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; alignment=&#8221;center&#8221;]<div data-id=\"mpc_flipbox-46a5723d400a0b\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-816a5723d401228\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum.jpg 550w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum-150x150.jpg 150w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum-300x300.jpg 300w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Lucidum-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1493672186102{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/buy-now\/\">Buy Now<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ganoderma-lucidum\/\">Product Details<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Ganoderma Lucidum&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-436a5723d4012e8\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-256a5723d4018cb\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium.jpg 550w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium-150x150.jpg 150w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium-300x300.jpg 300w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Mycelium-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1493672222830{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/buy-now\/\">Buy Now<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ganoderma-lucidum-mycelium\/\">Product Details<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Ganoderma Mycelium&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-426a5723d40197b\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-526a5723d401f2f\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder.jpg 550w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder-150x150.jpg 150w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder-300x300.jpg 300w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2016\/06\/Sporepowder-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1521647397188{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/buy-now\/\">Buy Now<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/ganoderma-spore-powder\/\">Product Details<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Spore Powder&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Ganoderma Lucidum&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Ganoderma Mycelium&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Spore Powder&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Body Management - Organo Gold<\/title>\n<meta name=\"description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.organogold.com\/ke-en\/body-management\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Body Management - Organo Gold\" \/>\n<meta property=\"og:description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.organogold.com\/ke-en\/body-management\/\" \/>\n<meta property=\"og:site_name\" content=\"Organo Gold\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/organogold\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-21T15:50:05+00:00\" \/>\n<meta property=\"fb:app_id\" content=\"1781016228881841\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OrganoGold\" \/>\n<meta name=\"twitter:site\" content=\"@OrganoGold\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/organogold.com\/ke-en\/#website\",\"url\":\"https:\/\/organogold.com\/ke-en\/\",\"name\":\"Organo Gold\",\"description\":\"Organo Gold\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/organogold.com\/ke-en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.organogold.com\/ke-en\/body-management\/#webpage\",\"url\":\"https:\/\/www.organogold.com\/ke-en\/body-management\/\",\"name\":\"Body Management - Organo Gold\",\"isPartOf\":{\"@id\":\"https:\/\/organogold.com\/ke-en\/#website\"},\"datePublished\":\"2016-06-22T22:42:36+00:00\",\"dateModified\":\"2018-03-21T15:50:05+00:00\",\"description\":\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.organogold.com\/ke-en\/body-management\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/organogold.com\/ke-en\/wp-json\/wp\/v2\/pages\/3581"}],"collection":[{"href":"https:\/\/organogold.com\/ke-en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/organogold.com\/ke-en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/organogold.com\/ke-en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/organogold.com\/ke-en\/wp-json\/wp\/v2\/comments?post=3581"}],"version-history":[{"count":0,"href":"https:\/\/organogold.com\/ke-en\/wp-json\/wp\/v2\/pages\/3581\/revisions"}],"wp:attachment":[{"href":"https:\/\/organogold.com\/ke-en\/wp-json\/wp\/v2\/media?parent=3581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}