{"id":83884,"date":"2016-06-23T11:39:36","date_gmt":"2016-06-23T15:39:36","guid":{"rendered":"http:\/\/www.organogold.com\/personal-care\/"},"modified":"2025-06-05T12:21:47","modified_gmt":"2025-06-05T19:21:47","slug":"personal-care","status":"publish","type":"page","link":"https:\/\/organogold.com\/za-en\/personal-care\/","title":{"rendered":"Personal Care"},"content":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; alignment=&#8221;center&#8221;]<div data-id=\"mpc_flipbox-746a576905103b1\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-746a57690510b9b\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"600\" height=\"600\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2020\/04\/OG-Essential-Soap.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2020\/04\/OG-Essential-Soap.jpg 600w, https:\/\/organogold.com\/wp-content\/uploads\/2020\/04\/OG-Essential-Soap-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2020\/04\/OG-Essential-Soap-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2020\/04\/OG-Essential-Soap-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2020\/04\/OG-Essential-Soap-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2020\/04\/OG-Essential-Soap-80x80.jpg 80w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1667847295208{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse ix-prodnum-3190\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">BUY NOW<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/premium-soap\/\">PRODUCT DETAILS<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Premium Cleansing Soap Bar&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;]<div data-id=\"mpc_flipbox-916a57690510c66\" class=\"mpc-flipbox mpc-init mpc-flipbox--flip-left \" ><div class=\"mpc-flipbox__content\" data-front-align=\"middle-center\" data-back-align=\"middle-center\"><div class=\"mpc-flipbox__front\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\"><div data-id=\"mpc_image-816a57690511223\" onclick=\"\" class=\"mpc-image mpc-init \" ><div class=\"mpc-item mpc-transition\"><img width=\"550\" height=\"550\" src=\"https:\/\/organogold.com\/wp-content\/uploads\/2025\/05\/Kai.jpg\" class=\"mpc-transition attachment-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/organogold.com\/wp-content\/uploads\/2025\/05\/Kai.jpg 550w, https:\/\/organogold.com\/wp-content\/uploads\/2025\/05\/Kai-146x146.jpg 146w, https:\/\/organogold.com\/wp-content\/uploads\/2025\/05\/Kai-50x50.jpg 50w, https:\/\/organogold.com\/wp-content\/uploads\/2025\/05\/Kai-75x75.jpg 75w, https:\/\/organogold.com\/wp-content\/uploads\/2025\/05\/Kai-85x85.jpg 85w, https:\/\/organogold.com\/wp-content\/uploads\/2025\/05\/Kai-80x80.jpg 80w\" sizes=\"(max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"mpc-flipbox__back mpc-container\"><div class=\"mpc-flipbox__wrapper\"><div class=\"mpc-flipbox-side\"><div class=\"mpc-flipbox-side__content\">[vc_column_text css=&#8221;.vc_custom_1749151302682{margin-right: 20px !important;margin-left: 20px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse ix-prodnum-3609\" title=\"\" href=\"#\" target=\"_blank\" rel=\"noopener noreferrer\">BUY NOW<\/a><\/p>\n<p style=\"text-align: center;\"><a class=\"vc_general vc_btn3 vc_btn3-size-sm vc_btn3-shape-square vc_btn3-style-outline vc_btn3-color-inverse\" title=\"\" href=\"..\/organo-kai\/\">PRODUCT DETAILS<\/a><\/p>\n<p>[\/vc_column_text]<\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Organo\u00ae Kai&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/3&#8243; alignment=&#8221;center&#8221;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Premium Cleansing Soap Bar&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][vc_column width=&#8221;1\/3&#8243;][vc_empty_space height=&#8221;10px&#8221;][vc_custom_heading text=&#8221;Organo\u00ae Kai&#8221; font_container=&#8221;tag:h3|text_align:center&#8221; google_fonts=&#8221;font_family:Roboto%20Slab%3A100%2C300%2Cregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;45px&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Personal Care - Organo Gold<\/title>\n<meta name=\"description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/organogold.com\/za-en\/personal-care\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Personal Care - Organo Gold\" \/>\n<meta property=\"og:description\" content=\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/organogold.com\/za-en\/personal-care\/\" \/>\n<meta property=\"og:site_name\" content=\"Organo Gold\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/organogold\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T19:21:47+00:00\" \/>\n<meta property=\"fb:app_id\" content=\"1781016228881841\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@OrganoGold\" \/>\n<meta name=\"twitter:site\" content=\"@OrganoGold\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/organogold.com\/za-en\/#website\",\"url\":\"https:\/\/organogold.com\/za-en\/\",\"name\":\"Organo Gold\",\"description\":\"Organo Gold\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/organogold.com\/za-en\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/organogold.com\/za-en\/personal-care\/#webpage\",\"url\":\"https:\/\/organogold.com\/za-en\/personal-care\/\",\"name\":\"Personal Care - Organo Gold\",\"isPartOf\":{\"@id\":\"https:\/\/organogold.com\/za-en\/#website\"},\"datePublished\":\"2016-06-23T15:39:36+00:00\",\"dateModified\":\"2025-06-05T19:21:47+00:00\",\"description\":\"ORGANO is a global leader in ganoderma-enhanced coffee and beverages, providing life changing opportunities with expanded portfolio in all-natural skincare, travel services, payment solutions and more.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/organogold.com\/za-en\/personal-care\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/organogold.com\/za-en\/wp-json\/wp\/v2\/pages\/83884"}],"collection":[{"href":"https:\/\/organogold.com\/za-en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/organogold.com\/za-en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/organogold.com\/za-en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/organogold.com\/za-en\/wp-json\/wp\/v2\/comments?post=83884"}],"version-history":[{"count":5,"href":"https:\/\/organogold.com\/za-en\/wp-json\/wp\/v2\/pages\/83884\/revisions"}],"predecessor-version":[{"id":91884,"href":"https:\/\/organogold.com\/za-en\/wp-json\/wp\/v2\/pages\/83884\/revisions\/91884"}],"wp:attachment":[{"href":"https:\/\/organogold.com\/za-en\/wp-json\/wp\/v2\/media?parent=83884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}